{"id":8991,"date":"2024-12-03T10:16:28","date_gmt":"2024-12-03T13:16:28","guid":{"rendered":"https:\/\/velinn.com\/?page_id=8991"},"modified":"2026-01-27T18:05:39","modified_gmt":"2026-01-27T21:05:39","slug":"pousada-cesar","status":"publish","type":"page","link":"https:\/\/velinn.com\/es\/pousada-cesar\/","title":{"rendered":"Velinn Pousada Cesar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8991\" class=\"elementor elementor-8991\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9602b34 e-con-full elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"9602b34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-eaa668f e-con-full e-flex e-con e-child\" data-id=\"eaa668f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a14ba38 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"a14ba38\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2a2b2d elementor-widget elementor-widget-text-editor\" data-id=\"b2a2b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"900\" class=\"elementor elementor-900\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-78ea766 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"78ea766\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:48,&quot;sticky_effects_offset&quot;:80,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2a51ec2 e-con-full efeito-vidro  e-flex e-con e-child\" data-id=\"2a51ec2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e7757d6 e-con-full e-flex e-con e-child\" data-id=\"e7757d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2bfc77 elementor-widget elementor-widget-heading\" data-id=\"f2bfc77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O MELHOR PRE\u00c7O GARANTIDO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb7df96 e-con-full e-flex e-con e-child\" data-id=\"cb7df96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2662cad elementor-widget__width-inherit elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"2662cad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;20&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Rerserva \" aria-label=\"Rerserva \">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"900\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"2662cad\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-cidade elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-cidade\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tDestino\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[cidade]\" id=\"form-field-cidade\" class=\"elementor-field-textual elementor-size-sm\">\n\t\t\t\t\t\t\t\t\t<option value=\"Todos\" selected=\"selected\">Todos<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ilhabela\">Ilhabela<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"S\u00e3o Sebasti\u00e3o\">S\u00e3o Sebasti\u00e3o<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ubatuba\">Ubatuba<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Angra Dos Reis\">Angra Dos Reis<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Campos do Jord\u00e3o\">Campos do Jord\u00e3o<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" Camanducaia\">Monte Verde <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Santo Ant\u00f4nio do Pinhal\">Santo Ant\u00f4nio do Pinhal<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Paraty\">Paraty<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" Foz do Iguacu\">Foz do Igua\u00e7u <\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-entrada elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-entrada\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tcheck-in\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[entrada]\" id=\"form-field-entrada\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field\" placeholder=\"check-in\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-saida elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-saida\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tcheck-out\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[saida]\" id=\"form-field-saida\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field\" placeholder=\"check-out\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-hospede elementor-col-20\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-hospede\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\th\u00f3spedes\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[hospede]\" id=\"form-field-hospede\" class=\"elementor-field-textual elementor-size-sm\">\n\t\t\t\t\t\t\t\t\t<option value=\" 1\">1 Adulto <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 2\" selected=\"selected\">2 Adultos <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 3\">3 Adultos <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 4\">4 Adultos <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 5\">5 Adultos <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 6\">6 Adultos <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 7\">7 Adultos <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\" 8\">8 Adultos <\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-20 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BUSCAR HOT\u00c9IS<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ede9390 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"ede9390\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4999637 elementor-widget elementor-widget-html\" data-id=\"4999637\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\nwindow.onload = function() {\r\n\r\njQuery(document).ready(function ($) {\r\n    function waitForFlatpicker(callback) {\r\n        if (typeof window.flatpickr !== 'function') {\r\n            setTimeout(function () { waitForFlatpicker(callback) }, 100);\r\n        }\r\n        callback();\r\n    }\r\n    waitForFlatpicker(function () {\r\n        flatpickr.l10ns.pt = {\r\n            weekdays: {\r\n                shorthand: [\"Dom\", \"Seg\", \"Ter\", \"Qua\", \"Qui\", \"Sex\", \"S\u00e1b\"],\r\n                longhand: [\r\n                    \"Domingo\",\r\n                    \"Segunda-feira\",\r\n                    \"Ter\u00e7a-feira\",\r\n                    \"Quarta-feira\",\r\n                    \"Quinta-feira\",\r\n                    \"Sexta-feira\",\r\n                    \"S\u00e1bado\",\r\n                ],\r\n            },\r\n            months: {\r\n                shorthand: [\r\n                    \"Jan\",\r\n                    \"Fev\",\r\n                    \"Mar\",\r\n                    \"Abr\",\r\n                    \"Mai\",\r\n                    \"Jun\",\r\n                    \"Jul\",\r\n                    \"Ago\",\r\n                    \"Set\",\r\n                    \"Out\",\r\n                    \"Nov\",\r\n                    \"Dez\",\r\n                ],\r\n                longhand: [\r\n                    \"Janeiro\",\r\n                    \"Fevereiro\",\r\n                    \"Mar\u00e7o\",\r\n                    \"Abril\",\r\n                    \"Maio\",\r\n                    \"Junho\",\r\n                    \"Julho\",\r\n                    \"Agosto\",\r\n                    \"Setembro\",\r\n                    \"Outubro\",\r\n                    \"Novembro\",\r\n                    \"Dezembro\",\r\n                ],\r\n            },\r\n\r\n            rangeSeparator: \" at\u00e9 \",\r\n            \r\n        };\r\n        \/\/set translations\r\n        flatpickr.localize(flatpickr.l10ns.pt);\r\n\r\n    });\r\n    \r\n    setTimeout(function () {\r\n      \/\/ Formato que ser\u00e1 exibido no formul\u00e1rio\r\n      var DATA_FORMATO_EXIBICAO = 'd\/m\/Y';\r\n      \/\/ Formato que ser\u00e1 enviado no redirect\r\n      var DATA_FORMATO_ENVIADO = \"d-m-Y\";\r\n      \/\/ N\u00famero m\u00ednimo de dias na sele\u00e7\u00e3o de datas\r\n      var MINIMO_DIAS = 1;\r\n\r\n      \/\/op\u00e7\u00f5es do form de check-in\r\n      var start = flatpickr('#form-field-entrada', {\r\n          minDate: \"today\",\r\n          disableMobile: true,\r\n          altInput: true,\r\n          altFormat: DATA_FORMATO_EXIBICAO,\r\n          dateFormat: DATA_FORMATO_ENVIADO,\r\n          onChange: function(selectedDates, dateStr, instance) {\r\n              if(dateStr) {\r\n                  endDate = end.parseDate(dateStr, DATA_FORMATO_ENVIADO);\r\n                  endDate.setDate(endDate.getDate() + MINIMO_DIAS);\r\n                  endDateStr = end.formatDate(endDate, DATA_FORMATO_ENVIADO);\r\n                  end.set('minDate', endDateStr);\r\n                  end.setDate(endDate);\r\n                  end.open();\r\n              }\r\n          }\r\n      });\r\n\r\n      \/\/op\u00e7\u00f5es do form de check-out\r\n      var end = flatpickr('#form-field-saida', {\r\n          minDate: \"today\",\r\n          disableMobile: true,\r\n          altInput: true,\r\n          altFormat: DATA_FORMATO_EXIBICAO,\r\n          dateFormat: DATA_FORMATO_ENVIADO\r\n      });\r\n\r\n      \/\/ Coloca data atual pre-preenchida\r\n      start.setDate(new Date());\r\n      end.setDate(new Date().setDate(new Date().getDate() + MINIMO_DIAS));\r\n        \r\n    }, 1000);\r\n});\r\n};\r\n\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecd47e0 e-flex e-con-boxed e-con e-parent\" data-id=\"ecd47e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00e2da2 elementor-widget elementor-widget-html\" data-id=\"00e2da2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n    \r\n        .wp-image-5035.shrink {\r\n        transform: scale(0.5);\r\n        \/* Diminui a imagem para 80% do tamanho original *\/\r\n    }\r\n<\/style>\r\n\r\n\r\n<script>\r\n    window.addEventListener('scroll', function () {\r\n        const image = document.querySelector('.wp-image-5035');\r\n\r\n        if (window.scrollY > 400) {\r\n            image.classList.add('shrink');\r\n        } else {\r\n            image.classList.remove('shrink');\r\n        }\r\n    });\r\n\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49bc821 e-con-full e-flex e-con e-child\" data-id=\"49bc821\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:120,&quot;sticky_effects_offset&quot;:1,&quot;sticky_offset_mobile&quot;:0,&quot;sticky_effects_offset_mobile&quot;:0,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-898d9c2 elementor-widget__width-initial scroll-image elementor-widget elementor-widget-image\" data-id=\"898d9c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Cesar_Pousada_Logo_Velinn-300x300-1.jpg\" class=\"attachment-full size-full wp-image-9005\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Cesar_Pousada_Logo_Velinn-300x300-1.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Cesar_Pousada_Logo_Velinn-300x300-1-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40a37b1 elementor-nav-menu__align-justify elementor-nav-menu--dropdown-none elementor-widget__width-initial elementor-widget elementor-widget-nav-menu\" data-id=\"40a37b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-40a37b1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5536\"><a href=\"#acomodacoes\" class=\"elementor-item elementor-item-anchor\">Acomoda\u00e7\u00f5es<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5538\"><a href=\"#localizacao\" class=\"elementor-item elementor-item-anchor\">Localiza\u00e7\u00e3o<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5535\"><a href=\"#informacoes\" class=\"elementor-item elementor-item-anchor\">Comodidades<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5539\"><a href=\"#depoimentos\" class=\"elementor-item elementor-item-anchor\">Avalia\u00e7\u00f5es de h\u00f3spedes<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-40a37b1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5536\"><a href=\"#acomodacoes\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Acomoda\u00e7\u00f5es<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5538\"><a href=\"#localizacao\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Localiza\u00e7\u00e3o<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5535\"><a href=\"#informacoes\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Comodidades<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5539\"><a href=\"#depoimentos\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Avalia\u00e7\u00f5es de h\u00f3spedes<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1726a34 e-flex e-con-boxed e-con e-parent\" data-id=\"1726a34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ed5cbb1 e-con-full e-flex e-con e-child\" data-id=\"ed5cbb1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0b8b061 e-con-full elementor-hidden-desktop elementor-hidden-laptop e-flex e-con e-child\" data-id=\"0b8b061\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9329fd8 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"9329fd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9329fd8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTAzMywidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS0yOC03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiOTMyOWZkOCJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-28-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-28-768x461-1-qxysjdegiz6r4kclk1ef8zrg041yzwijd98vkhz0c0.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-28-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9329fd8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTAzNSwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS0zNi03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiOTMyOWZkOCJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-36-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-36-768x461-1-qxysjg7z3ham3e8i3kmayh1ts9o2mztqdn7c0buttc.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-36-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9329fd8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTAzNywidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS00My03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiOTMyOWZkOCJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-43-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-43-768x461-1-qxysjqk76norn3thf7377wfwbi93znys32doadfhww.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-43-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9329fd8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTAzOSwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS02My03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiOTMyOWZkOCJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-63-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-63-768x461-1-qxysjw78bnwhkrlai9iymv0nvthb9ul63ual6174vk.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-63-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9329fd8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTA0MCwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS02Ni03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiOTMyOWZkOCJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-66-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-66-768x461-1-qxysjz0qw60cjlh71squccb1nz3ewxwd4891lv2ycw.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-66-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9329fd8\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTAzMSwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS03LTc2OHg0NjEtMS5qcGciLCJzbGlkZXNob3ciOiI5MzI5ZmQ4In0%3D\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-7-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-7-768x461-1-qxysj24e8yrb98szdwiwf2lwvhlkfj9rbpf1t6fqeo.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-7-768x461\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b889b66 e-con-full e-flex e-con e-child\" data-id=\"b889b66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ae49aa9 e-con-full e-flex e-con e-child\" data-id=\"ae49aa9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4570d47 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4570d47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rodovia SP50, Km 163-S\/N, Santo Ant\u00f4nio do Pinhal, CEP 12450-000, Brasil<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-696797e e-con-full e-flex e-con e-child\" data-id=\"696797e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0617abd elementor-mobile-align-center elementor-align-right botaodoliwis elementor-widget elementor-widget-button\" data-id=\"0617abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SIMULAR RESERVA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-147f0c2 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"147f0c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-11e78ae e-con-full e-flex e-con e-child\" data-id=\"11e78ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6000344 e-con-full e-flex e-con e-child\" data-id=\"6000344\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cac9c09 elementor-widget elementor-widget-image\" data-id=\"cac9c09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-3-qxysfxbrha80npoqadhdczmk5kalctiiu8w00vmluq.jpg\" title=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-3\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-3\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bd00d2 e-con-full e-flex e-con e-child\" data-id=\"1bd00d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-af414b4 e-con-full e-flex e-con e-child\" data-id=\"af414b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2bf1db elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f2bf1db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-83-768x461-1.jpg\" class=\"attachment-full size-full wp-image-9048\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-83-768x461-1.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-83-768x461-1-300x180.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a94ef7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"2a94ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-8-768x461-1.jpg\" class=\"attachment-full size-full wp-image-9055\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-8-768x461-1.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-8-768x461-1-300x180.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89d1261 e-con-full e-flex e-con e-child\" data-id=\"89d1261\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6416a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9a6416a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"480\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-73-1024x614.jpg\" class=\"attachment-large size-large wp-image-9043\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-73-1024x614.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-73-300x180.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-73-768x461.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-73.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-980603f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"980603f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-36-768x461-1.jpg\" class=\"attachment-large size-large wp-image-9035\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-36-768x461-1.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-36-768x461-1-300x180.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff0a18c e-con-full e-flex e-con e-child\" data-id=\"ff0a18c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f486a21 elementor-widget elementor-widget-image\" data-id=\"f486a21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-1-768x461-1-qxyskvx2biftarb3mmqp3bhsnfh86tcvtzi778706w.jpg\" title=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-1-768\u00d7461\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-1-768x461\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1ddc2b elementor-widget elementor-widget-image\" data-id=\"c1ddc2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-66-768x461-1-qxysjz0pob6s0emvyqir61snuxzdpeqa1go7ejjs8o.jpg\" title=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-66-768\u00d7461\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-66-768x461\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-967b061 elementor-widget elementor-widget-image\" data-id=\"967b061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-63-768x461-1-qxysjw773t2x1kqzf7avgkia2sda2bf312pqypnyrc.jpg\" title=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-63-768\u00d7461\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-63-768x461\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ae5c76 elementor-widget elementor-widget-image\" data-id=\"7ae5c76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-12-768x461-1-qxysldrzxd49fcl5qcglwozjxr1792bs8fwfbhgiwo.jpg\" title=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-12-768\u00d7461\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-12-768x461\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-105f5e2 e-con-full e-flex e-con e-child\" data-id=\"105f5e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba776ea elementor-widget elementor-widget-image\" data-id=\"ba776ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijk1MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-6-768x461-1-qxysl69aeotyugw2y97lcqvv6o29jhhxjeojh9roag.jpg\" title=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-6-768\u00d7461\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-6-768x461\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">mais 37 fotos<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c7e83b e-flex e-con-boxed e-con e-parent\" data-id=\"1c7e83b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a4393a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4a4393a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Destaques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1ad600 e-con-full e-flex e-con e-child\" data-id=\"e1ad600\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fae932c e-con-full e-flex e-con e-child\" data-id=\"fae932c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6437eda elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6437eda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/restaurante.png\" class=\"attachment-full size-full wp-image-9102\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/restaurante.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/restaurante-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/restaurante-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Restaurante<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba4de32 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ba4de32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/piscina-1-1.png\" class=\"attachment-full size-full wp-image-6009\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/piscina-1-1.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/piscina-1-1-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/piscina-1-1-150x150.png 150w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/elementor\/thumbs\/piscina-1-1-150x150.png 600w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Duas Piscinas<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77ad2c7 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"77ad2c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/pata.png\" class=\"attachment-full size-full wp-image-8524\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/pata.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/pata-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/pata-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pet Friendly<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9d8ef0 e-con-full e-flex e-con e-child\" data-id=\"c9d8ef0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff421b6 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ff421b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2025\/06\/sinal-wifi.png\" class=\"attachment-full size-full wp-image-35517\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2025\/06\/sinal-wifi.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/06\/sinal-wifi-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/06\/sinal-wifi-150x150.png 150w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/06\/sinal-wifi-12x12.png 12w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/06\/elementor\/thumbs\/sinal-wifi-150x150.png 600w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/06\/elementor\/thumbs\/sinal-wifi-150x150.png 1800w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Wi-Fi<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7c723c elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b7c723c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/familia.png\" class=\"attachment-full size-full wp-image-8461\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/familia.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/familia-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/familia-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Quartos para fam\u00edlias<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7edd33 elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d7edd33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/cafe-da-manha.png\" class=\"attachment-full size-full wp-image-6016\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/cafe-da-manha.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/cafe-da-manha-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/11\/cafe-da-manha-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Caf\u00e9 da Manh\u00e3<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d5c87d e-flex e-con-boxed e-con e-parent\" data-id=\"5d5c87d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec4412a elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"ec4412a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 7\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ec4412a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTA1NiwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9SZXN0YXVyYW50ZS0xMi03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiZWM0NDEyYSJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-12-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-12-768x461-1-qxyslds157xtyjfgteop2zhxqs58glhvb7h9iszp0w.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-12-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 7\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ec4412a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTA1NSwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9SZXN0YXVyYW50ZS04LTc2OHg0NjEtMS5qcGciLCJzbGlkZXNob3ciOiJlYzQ0MTJhIn0%3D\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-8-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-8-768x461-1-qxyslayikptyzpjk9vgtdi7jymj4ti6oatit2z3vjk.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-8-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 7\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ec4412a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTA1NCwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9SZXN0YXVyYW50ZS02LTc2OHg0NjEtMS5qcGciLCJzbGlkZXNob3ciOiJlYzQ0MTJhIn0%3D\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-6-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-6-768x461-1-qxysl69bmjnjdnqe1bfoj1e8zp6ar0o0m69dolaueo.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-6-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 7\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ec4412a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTA1MywidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9SZXN0YXVyYW50ZS01LTc2OHg0NjEtMS5qcGciLCJzbGlkZXNob3ciOiJlYzQ0MTJhIn0%3D\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-5-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-5-768x461-1-qxysl3ft21joetuhhs7stk3v7jk73xctlsax8rf0xc.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-5-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 7\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ec4412a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTA1MiwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9SZXN0YXVyYW50ZS0yLTc2OHg0NjEtMS5qcGciLCJzbGlkZXNob3ciOiJlYzQ0MTJhIn0%3D\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-2-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-2-768x461-1-qxyskyqm3vd8ss1b986nz3ak8m7d1fu5x51hudlzsg.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Restaurante-2-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 7\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ec4412a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTA0OSwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS04Ni03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiZWM0NDEyYSJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-86-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-86-768x461-1-qxyskt3kyv5iv49i65qwk4psoaz5r97rwd4kypucts.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-86-768x461\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 7\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ec4412a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTAzOCwidXJsIjoiaHR0cHM6XC9cL3ZlbGlubi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzEyXC9WZWxpbm5fUG91c2FkYV9DZXNhcl9TYW50b19BbnRvbmlvX2RvX1BpbmhhbF9Qcm9wcmllZGFkZS01OC03Njh4NDYxLTEuanBnIiwic2xpZGVzaG93IjoiZWM0NDEyYSJ9\" href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-58-768x461-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-58-768x461-1-qxysjtdpr5smlxpdyqb2xdqa3nv7mr9z3gc4q7bbe8.jpg\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-58-768x461\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7720932 e-con-full e-flex e-con e-child\" data-id=\"7720932\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dabdb1b animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dabdb1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">um pouco mais<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a6f829 elementor-widget elementor-widget-text-editor\" data-id=\"2a6f829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com mais de 70 anos de hist\u00f3ria, a Velinn Pousada C\u00e9sar \u00e9 o ref\u00fagio perfeito para quem busca tranquilidade e conforto em meio \u00e0 natureza. Situada na charmosa Santo Ant\u00f4nio do Pinhal, nossa pousada combina charme e conforto com um estilo r\u00fastico. Aqui, o tempo passa mais devagar e nossa decora\u00e7\u00e3o com m\u00f3veis de \u00e9poca te far\u00e3o viajar no tempo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea2e19f e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"ea2e19f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4e913b elementor-widget elementor-widget-text-editor\" data-id=\"b4e913b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Somos\u00a0<a href=\"\/pets\">Pet Friendly<\/a>, ent\u00e3o traga seu amigo de quatro patas para desfrutar de momentos especiais ao seu lado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e06161 elementor-mobile-align-center elementor-align-right botaodoliwis elementor-widget elementor-widget-button\" data-id=\"2e06161\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SIMULAR RESERVA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65afb3c e-flex e-con-boxed e-con e-parent\" data-id=\"65afb3c\" data-element_type=\"container\" data-e-type=\"container\" id=\"acomodacoes\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43d91fd animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"43d91fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">infraestrutura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5591cc8 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5591cc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACOMODA\u00c7\u00d5ES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bafd1bd elementor-arrows-position-outside elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"bafd1bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;33d4717&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;48a0dba&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;4c24f43&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;8f3976f&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;ee59670&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;f226fb7&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;f084544&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;a5e96a3&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;e0619f5&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;7e92878&quot;}],&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7690e64 e-flex e-con-boxed e-con e-child\" data-id=\"7690e64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5415e3c elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"5415e3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45f76741  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45f76741\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45f76741\" class=\"tp-row post-inner-loop post6a56c45f76741\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-7.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"5415e3c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-7.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-7-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-7-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-7-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-7-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-5415e3c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-1.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"5415e3c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-1.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-1-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-1-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-1-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-5415e3c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-3.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"5415e3c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-3.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-3-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-3-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-3-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Junior-3-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-5415e3c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ae9cb1 e-con-full e-flex e-con e-child\" data-id=\"1ae9cb1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d828289 e-con-full e-flex e-con e-child\" data-id=\"d828289\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a88954d animated-slow elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a88954d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto J\u00fanior<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c7c042 e-con-full e-flex e-con e-child\" data-id=\"3c7c042\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-782bf58 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"782bf58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 2 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Camas de casal <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c535a30 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c535a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">20 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60d149b elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"60d149b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fd63f6 e-flex e-con-boxed e-con e-child\" data-id=\"4fd63f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4304e34 elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"4304e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45f7d68c  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45f7d68c\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45f7d68c\" class=\"tp-row post-inner-loop post6a56c45f7d68c\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-7.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4304e34\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-7.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-7-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-7-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-7-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-7-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4304e34\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-4.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4304e34\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-4.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-4-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-4-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-4-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4304e34\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-6.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4304e34\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-6.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-6-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-6-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-6-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-6-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4304e34\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-8.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4304e34\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-8.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-8-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-8-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-8-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Standard-8-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4304e34\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b165f2 e-con-full e-flex e-con e-child\" data-id=\"1b165f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6756277 e-con-full e-flex e-con e-child\" data-id=\"6756277\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04f62af animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"04f62af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Standard<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-516bf46 e-con-full e-flex e-con e-child\" data-id=\"516bf46\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a979bdf elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a979bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 3 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 1 de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d602bda elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d602bda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a87676e elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"a87676e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-920f50c e-flex e-con-boxed e-con e-child\" data-id=\"920f50c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-087dc23 elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"087dc23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45f8a69b  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45f8a69b\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45f8a69b\" class=\"tp-row post-inner-loop post6a56c45f8a69b\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-6-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-2-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-3-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-5-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-8-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-9-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-10-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-12-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-13-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-1-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-2-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-9-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-10-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-13-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-14-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-17-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-18-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-20-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-21-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-22-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-23-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo-Standard-11-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"087dc23\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Duplo_Standard-11-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-087dc23\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2e4ad0 e-con-full e-flex e-con e-child\" data-id=\"f2e4ad0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d568fd8 e-con-full e-flex e-con e-child\" data-id=\"d568fd8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f981e9 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6f981e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Duplo Standard<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12ff395 e-con-full e-flex e-con e-child\" data-id=\"12ff395\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbcf09f elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dbcf09f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 2 camas de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-couch\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M160 224v64h320v-64c0-35.3 28.7-64 64-64h32c0-53-43-96-96-96H160c-53 0-96 43-96 96h32c35.3 0 64 28.7 64 64zm416-32h-32c-17.7 0-32 14.3-32 32v96H128v-96c0-17.7-14.3-32-32-32H64c-35.3 0-64 28.7-64 64 0 23.6 13 44 32 55.1V432c0 8.8 7.2 16 16 16h64c8.8 0 16-7.2 16-16v-16h384v16c0 8.8 7.2 16 16 16h64c8.8 0 16-7.2 16-16V311.1c19-11.1 32-31.5 32-55.1 0-35.3-28.7-64-64-64z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 ambientes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3daf8df elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3daf8df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> 26 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a583c49 elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"a583c49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57177cd e-flex e-con-boxed e-con e-child\" data-id=\"57177cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c9c77 elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"d7c9c77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45f99961  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45f99961\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45f99961\" class=\"tp-row post-inner-loop post6a56c45f99961\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-1.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-1.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-1-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-1-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-1-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-2.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-2.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-2-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-2-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-2-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-4.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-4.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-4-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-4-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-4-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-5.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-5.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-5-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-5-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-5-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-5-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-6.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-6.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-6-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-6-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-6-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-6-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-11.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-11.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-11-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-11-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-11-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-11-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-13.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-13.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-13.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-13-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-13-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-13-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-13-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-18.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"d7c9c77\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-18.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-18.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-18-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-18-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-18-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Familia-18-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-d7c9c77\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ac857a e-con-full e-flex e-con e-child\" data-id=\"8ac857a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0aca591 e-con-full e-flex e-con e-child\" data-id=\"0aca591\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9e9209 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c9e9209\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Fam\u00edlia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-827b428 e-con-full e-flex e-con e-child\" data-id=\"827b428\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c72de51 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c72de51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 5 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 3 camas de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-couch\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M160 224v64h320v-64c0-35.3 28.7-64 64-64h32c0-53-43-96-96-96H160c-53 0-96 43-96 96h32c35.3 0 64 28.7 64 64zm416-32h-32c-17.7 0-32 14.3-32 32v96H128v-96c0-17.7-14.3-32-32-32H64c-35.3 0-64 28.7-64 64 0 23.6 13 44 32 55.1V432c0 8.8 7.2 16 16 16h64c8.8 0 16-7.2 16-16v-16h384v16c0 8.8 7.2 16 16 16h64c8.8 0 16-7.2 16-16V311.1c19-11.1 32-31.5 32-55.1 0-35.3-28.7-64-64-64z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 ambientes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a1c01b elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9a1c01b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pagelines\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M384 312.7c-55.1 136.7-187.1 54-187.1 54-40.5 81.8-107.4 134.4-184.6 134.7-16.1 0-16.6-24.4 0-24.4 64.4-.3 120.5-42.7 157.2-110.1-41.1 15.9-118.6 27.9-161.6-82.2 109-44.9 159.1 11.2 178.3 45.5 9.9-24.4 17-50.9 21.6-79.7 0 0-139.7 21.9-149.5-98.1 119.1-47.9 152.6 76.7 152.6 76.7 1.6-16.7 3.3-52.6 3.3-53.4 0 0-106.3-73.7-38.1-165.2 124.6 43 61.4 162.4 61.4 162.4.5 1.6.5 23.8 0 33.4 0 0 45.2-89 136.4-57.5-4.2 134-141.9 106.4-141.9 106.4-4.4 27.4-11.2 53.4-20 77.5 0 0 83-91.8 172-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vistas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-542f2a1 elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"542f2a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5d5a57 e-flex e-con-boxed e-con e-child\" data-id=\"d5d5a57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf0b137 elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"cf0b137\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45fa2ebe  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45fa2ebe\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45fa2ebe\" class=\"tp-row post-inner-loop post6a56c45fa2ebe\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-6.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"cf0b137\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-6.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-6-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-6-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-6-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-6-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-cf0b137\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-4.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"cf0b137\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-4.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-4-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-4-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-4-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-cf0b137\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-2.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"cf0b137\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-2.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-2-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-2-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-2-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-cf0b137\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-1.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"cf0b137\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-1.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-1-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-1-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-1-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-cf0b137\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-14.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"cf0b137\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-14.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-14.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-14-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-14-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-14-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Luxo-14-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-cf0b137\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8052be e-con-full e-flex e-con e-child\" data-id=\"c8052be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cb80d9d e-con-full e-flex e-con e-child\" data-id=\"cb80d9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8c1699 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c8c1699\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Luxo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-addfe15 e-con-full e-flex e-con e-child\" data-id=\"addfe15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcd9d77 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dcd9d77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d032af4 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d032af4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a81b7b4 elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"a81b7b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ddd50a e-flex e-con-boxed e-con e-child\" data-id=\"6ddd50a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d83d85 elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"1d83d85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45faa915  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45faa915\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45faa915\" class=\"tp-row post-inner-loop post6a56c45faa915\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-2.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"1d83d85\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-2.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-2-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-2-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-2-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-1d83d85\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-4.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"1d83d85\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-4.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-4-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-4-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-4-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-1d83d85\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-6.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"1d83d85\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-6.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-6-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-6-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-6-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Economico-6-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-1d83d85\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fdcac3 e-con-full e-flex e-con e-child\" data-id=\"7fdcac3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e06887 e-con-full e-flex e-con e-child\" data-id=\"4e06887\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e59923 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2e59923\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Econ\u00f4mico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fed96b3 e-con-full e-flex e-con e-child\" data-id=\"fed96b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d854cb elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8d854cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 4 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 2 camas de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be85e99 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"be85e99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pagelines\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M384 312.7c-55.1 136.7-187.1 54-187.1 54-40.5 81.8-107.4 134.4-184.6 134.7-16.1 0-16.6-24.4 0-24.4 64.4-.3 120.5-42.7 157.2-110.1-41.1 15.9-118.6 27.9-161.6-82.2 109-44.9 159.1 11.2 178.3 45.5 9.9-24.4 17-50.9 21.6-79.7 0 0-139.7 21.9-149.5-98.1 119.1-47.9 152.6 76.7 152.6 76.7 1.6-16.7 3.3-52.6 3.3-53.4 0 0-106.3-73.7-38.1-165.2 124.6 43 61.4 162.4 61.4 162.4.5 1.6.5 23.8 0 33.4 0 0 45.2-89 136.4-57.5-4.2 134-141.9 106.4-141.9 106.4-4.4 27.4-11.2 53.4-20 77.5 0 0 83-91.8 172-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">vista para o jardim.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e67087 elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"0e67087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"7\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ea1ca2 e-flex e-con-boxed e-con e-child\" data-id=\"6ea1ca2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4641b5c elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"4641b5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45fb178c  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45fb178c\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45fb178c\" class=\"tp-row post-inner-loop post6a56c45fb178c\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-9.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4641b5c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-9.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-9-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-9-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-9-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-9-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4641b5c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-7.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4641b5c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-7.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-7-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-7-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-7-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-7-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4641b5c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-3.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4641b5c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-3.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-3-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-3-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-3-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-3-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4641b5c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-8.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4641b5c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-8.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-8-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-8-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-8-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-8-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4641b5c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-10.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4641b5c\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-10.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-10.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-10-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-10-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-10-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Familia-10-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4641b5c\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f6397d e-con-full e-flex e-con e-child\" data-id=\"3f6397d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cf84509 e-con-full e-flex e-con e-child\" data-id=\"cf84509\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e7b87f animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0e7b87f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Su\u00edte Fam\u00edlia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fea7d07 e-con-full e-flex e-con e-child\" data-id=\"fea7d07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d073fe4 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d073fe4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 5 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 3 camas de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-794ba8a elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"794ba8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> 30 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pagelines\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M384 312.7c-55.1 136.7-187.1 54-187.1 54-40.5 81.8-107.4 134.4-184.6 134.7-16.1 0-16.6-24.4 0-24.4 64.4-.3 120.5-42.7 157.2-110.1-41.1 15.9-118.6 27.9-161.6-82.2 109-44.9 159.1 11.2 178.3 45.5 9.9-24.4 17-50.9 21.6-79.7 0 0-139.7 21.9-149.5-98.1 119.1-47.9 152.6 76.7 152.6 76.7 1.6-16.7 3.3-52.6 3.3-53.4 0 0-106.3-73.7-38.1-165.2 124.6 43 61.4 162.4 61.4 162.4.5 1.6.5 23.8 0 33.4 0 0 45.2-89 136.4-57.5-4.2 134-141.9 106.4-141.9 106.4-4.4 27.4-11.2 53.4-20 77.5 0 0 83-91.8 172-20z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sacada <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd656c2 elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"bd656c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"8\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc6a47f e-flex e-con-boxed e-con e-child\" data-id=\"cc6a47f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4522466 elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"4522466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45fb9043  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45fb9043\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45fb9043\" class=\"tp-row post-inner-loop post6a56c45fb9043\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-4-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-3-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Velinn Pousada C\u00e9sar - Hospedagem em Santo Ant\u00f4nio do Pinhal\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-5-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-scaled.jpg\" class=\"attachment-full size-full\" alt=\"Velinn Pousada C\u00e9sar - Hospedagem em Santo Ant\u00f4nio do Pinhal\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-2-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-7-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-9-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-10-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-11-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-12-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-14-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-15-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-18-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-1-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-scaled.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"4522466\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-scaled.jpg 2560w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-1536x1024.jpg 1536w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-2048x1365.jpg 2048w, https:\/\/velinn.com\/wp-content\/uploads\/2026\/01\/Velinn_-Cesar_Master-8-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-4522466\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0dd0ea e-con-full e-flex e-con e-child\" data-id=\"b0dd0ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0db73d2 e-con-full e-flex e-con e-child\" data-id=\"0db73d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bd4034 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1bd4034\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Master<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bee3295 e-con-full e-flex e-con e-child\" data-id=\"bee3295\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-541e85e elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"541e85e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 4 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 2 camas de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9c49e0 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e9c49e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e02da0b elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"e02da0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"9\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db0ed9d e-flex e-con-boxed e-con e-child\" data-id=\"db0ed9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d68b08 elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"8d68b08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45fc465c  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45fc465c\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45fc465c\" class=\"tp-row post-inner-loop post6a56c45fc465c\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-4.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d68b08\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-4.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-4-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-4-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-4-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-8d68b08\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-5.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d68b08\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-5.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-5-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-5-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-5-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-5-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-8d68b08\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-6.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d68b08\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-6.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-6-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-6-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-6-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-6-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-8d68b08\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-8.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d68b08\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-8.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-8-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-8-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-8-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Quarto_Superior-8-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-8d68b08\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78b49e0 e-con-full e-flex e-con e-child\" data-id=\"78b49e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e04d1a7 e-con-full e-flex e-con e-child\" data-id=\"e04d1a7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d61b5a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4d61b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Superior<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8edda64 e-con-full e-flex e-con e-child\" data-id=\"8edda64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c334200 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c334200\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 3 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 1 cama de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d23f893 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d23f893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> 40 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ffd08f elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"6ffd08f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"10\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 10\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ec4b57 e-flex e-con-boxed e-con e-child\" data-id=\"1ec4b57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c958eb elementor-widget elementor-widget-tp-gallery-listout\" data-id=\"6c958eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-gallery-listout.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pt-plus-gallery-list\" class=\"gallery-list post6a56c45fcc2b8  list-carousel-slick gallery-style-1 hover-image-style-1  tp-gal-fc\"   data-slider_direction=\"false\" data-slide_speed=\"1500\" data-slider_desktop_column=\"1\" data-steps_slide=\"1\" data-slider_draggable=\"true\" data-multi_drag=\"false\" data-slider_infinite=\"false\" data-slider_pause_hover=\"false\" data-slider_adaptive_height=\"false\" data-slider_animation=\"ease\" data-slider_autoplay=\"false\" data-autoplay_speed=\"0\" data-slider_tablet_column=\"1\" data-tablet_steps_slide=\"1\" data-slider_responsive_tablet=\"no\" data-slider_mobile_column=\"1\" data-mobile_steps_slide=\"1\" data-slider_responsive_mobile=\"no\" data-slider_dots=\"true\" data-slider_dots_style=\"slick-dots style-1\" data-slider_arrows=\"false\" data-slider_arrows_style=\"\"  data-arrows_position=\"\"  data-arrow_bg_color=\"\"  data-arrow_icon_color=\"\"  data-arrow_hover_bg_color=\"\"  data-arrow_hover_icon_color=\"\"  data-slider_center_mode=\"false\"  data-center_padding=\"0\"  data-scale_center_slide=\"1\"  data-scale_normal_slide=\"0.8\"  data-opacity_normal_slide=\"0.7\"  data-slider_rows=\"1\"  data-id=\"post6a56c45fcc2b8\" data-style=\"style-1\"  data-result=\"{&quot;carousel_direction&quot;:&quot;ltr&quot;}\" dir=ltr data-enable-isotope=\"1\"><div id=\"post6a56c45fcc2b8\" class=\"tp-row post-inner-loop post6a56c45fcc2b8\"><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-15.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"6c958eb\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-15.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-15.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-15-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-15-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-15-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-15-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-6c958eb\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-13.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"6c958eb\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-13.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-13.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-13-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-13-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-13-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-13-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-6c958eb\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-5.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"6c958eb\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-5.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-5-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-5-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-5-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-5-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-6c958eb\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-4.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"6c958eb\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-4.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-4-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-4-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-4-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-6c958eb\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"grid-item metro-item0       \"  ><div>\n\t\t\t<a href=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-11.jpg\" class=\"gallery-list-content\" data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"6c958eb\">\n\t\t\t\n\t<div class=\"post-content-image\">\n\t\t\n<div class=\"gallery-image\">\n\t<span class=\"thumb-wrap\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-11.jpg 1600w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-11-300x200.jpg 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-11-1024x683.jpg 1024w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-11-768x512.jpg 768w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Suite_Exclusiva-11-1536x1024.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t<\/span>\n<\/div>\n\t<\/div>\n\n\t\t<div class=\"post-content-center\">\t\t\n\t\t<div class=\"post-hover-content\">\n\t\t\t<div class=\"meta-search-icon\">\n\t\t\t<div data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"icn-6c958eb\"><i class=\"fas fa-search-plus\" aria-hidden=\"true\"><\/i><\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e3762f e-con-full e-flex e-con e-child\" data-id=\"9e3762f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ec83871 e-con-full e-flex e-con e-child\" data-id=\"ec83871\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa8a7f1 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fa8a7f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quarto Exclusivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a89f517 e-con-full e-flex e-con e-child\" data-id=\"a89f517\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2627fc elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b2627fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">at\u00e9 6 pessoas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-couch\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M160 224v64h320v-64c0-35.3 28.7-64 64-64h32c0-53-43-96-96-96H160c-53 0-96 43-96 96h32c35.3 0 64 28.7 64 64zm416-32h-32c-17.7 0-32 14.3-32 32v96H128v-96c0-17.7-14.3-32-32-32H64c-35.3 0-64 28.7-64 64 0 23.6 13 44 32 55.1V432c0 8.8 7.2 16 16 16h64c8.8 0 16-7.2 16-16v-16h384v16c0 8.8 7.2 16 16 16h64c8.8 0 16-7.2 16-16V311.1c19-11.1 32-31.5 32-55.1 0-35.3-28.7-64-64-64z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3 Ambientes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bed\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 256c44.11 0 80-35.89 80-80s-35.89-80-80-80-80 35.89-80 80 35.89 80 80 80zm352-128H304c-8.84 0-16 7.16-16 16v144H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v352c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-48h512v48c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16V240c0-61.86-50.14-112-112-112z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 cama de casal + 4 camas de solteiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bcf4d2 elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8bcf4d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-usb\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M641.5 256c0 3.1-1.7 6.1-4.5 7.5L547.9 317c-1.4.8-2.8 1.4-4.5 1.4-1.4 0-3.1-.3-4.5-1.1-2.8-1.7-4.5-4.5-4.5-7.8v-35.6H295.7c25.3 39.6 40.5 106.9 69.6 106.9H392V354c0-5 3.9-8.9 8.9-8.9H490c5 0 8.9 3.9 8.9 8.9v89.1c0 5-3.9 8.9-8.9 8.9h-89.1c-5 0-8.9-3.9-8.9-8.9v-26.7h-26.7c-75.4 0-81.1-142.5-124.7-142.5H140.3c-8.1 30.6-35.9 53.5-69 53.5C32 327.3 0 295.3 0 256s32-71.3 71.3-71.3c33.1 0 61 22.8 69 53.5 39.1 0 43.9 9.5 74.6-60.4C255 88.7 273 95.7 323.8 95.7c7.5-20.9 27-35.6 50.4-35.6 29.5 0 53.5 23.9 53.5 53.5s-23.9 53.5-53.5 53.5c-23.4 0-42.9-14.8-50.4-35.6H294c-29.1 0-44.3 67.4-69.6 106.9h310.1v-35.6c0-3.3 1.7-6.1 4.5-7.8 2.8-1.7 6.4-1.4 8.9.3l89.1 53.5c2.8 1.1 4.5 4.1 4.5 7.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomada perto da cama<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-crop-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M488 352h-40V96c0-17.67-14.33-32-32-32H192v96h160v328c0 13.25 10.75 24 24 24h48c13.25 0 24-10.75 24-24v-40h40c13.25 0 24-10.75 24-24v-48c0-13.26-10.75-24-24-24zM160 24c0-13.26-10.75-24-24-24H88C74.75 0 64 10.74 64 24v40H24C10.75 64 0 74.74 0 88v48c0 13.25 10.75 24 24 24h40v256c0 17.67 14.33 32 32 32h224v-96H160V24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">30 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tshirt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M631.2 96.5L436.5 0C416.4 27.8 371.9 47.2 320 47.2S223.6 27.8 203.5 0L8.8 96.5c-7.9 4-11.1 13.6-7.2 21.5l57.2 114.5c4 7.9 13.6 11.1 21.5 7.2l56.6-27.7c10.6-5.2 23 2.5 23 14.4V480c0 17.7 14.3 32 32 32h256c17.7 0 32-14.3 32-32V226.3c0-11.8 12.4-19.6 23-14.4l56.6 27.7c7.9 4 17.5.8 21.5-7.2L638.3 118c4-7.9.8-17.6-7.1-21.5z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-fire-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M323.56 51.2c-20.8 19.3-39.58 39.59-56.22 59.97C240.08 73.62 206.28 35.53 168 0 69.74 91.17 0 209.96 0 281.6 0 408.85 100.29 512 224 512s224-103.15 224-230.4c0-53.27-51.98-163.14-124.44-230.4zm-19.47 340.65C282.43 407.01 255.72 416 226.86 416 154.71 416 96 368.26 96 290.75c0-38.61 24.31-72.63 72.79-130.75 6.93 7.98 98.83 125.34 98.83 125.34l58.63-66.88c4.14 6.85 7.91 13.55 11.27 19.97 27.35 52.19 15.81 118.97-33.43 153.42z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d78d44 elementor-mobile-align-justify elementor-align-justify botaodoliwis elementor-widget elementor-widget-button\" data-id=\"1d78d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinnpousadacesar.velinn.com\/Booking?companyId=65c152f63965f70b5e755b13&#038;utm_source=sitevelinn&#038;utm_medium=rede&#038;utm_campaign=&#038;utm_term=&#038;utm_content=botao\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR AGORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a8740a e-flex e-con-boxed e-con e-parent\" data-id=\"1a8740a\" data-element_type=\"container\" data-e-type=\"container\" id=\"informacoes\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e32638 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5e32638\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comodidades e Informa\u00e7\u00f5es de hospedagem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f50b5 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"57f50b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fique por dentro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddbc5dc elementor-widget elementor-widget-n-accordion\" data-id=\"ddbc5dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2320\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2320\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comodidades <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2320\" class=\"elementor-element elementor-element-59bae6a e-con-full e-flex e-con e-child\" data-id=\"59bae6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2f0f65 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c2f0f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principais comodidades<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2320\" class=\"elementor-element elementor-element-6072008 e-flex e-con-boxed e-con e-child\" data-id=\"6072008\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64c8e6a elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"64c8e6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-swimming-pool\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 416h-16c-26.04 0-45.8-8.42-56.09-17.9-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C461.8 407.58 442.04 416 416 416s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C269.8 407.58 250.04 416 224 416s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C77.8 407.58 58.04 416 32 416H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h16c38.62 0 72.72-12.19 96-31.84 23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84h16c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zm-400-32v-96h192v96c19.12 0 30.86-6.16 34.39-9.42 9.17-8.46 19.2-14.34 29.61-18.07V128c0-17.64 14.36-32 32-32s32 14.36 32 32v16c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-16c0-52.94-43.06-96-96-96s-96 43.06-96 96v96H224v-96c0-17.64 14.36-32 32-32s32 14.36 32 32v16c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-16c0-52.94-43.06-96-96-96s-96 43.06-96 96v228.5c10.41 3.73 20.44 9.62 29.61 18.07 3.53 3.27 15.27 9.43 34.39 9.43z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Piscina ao ar livre<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-parking\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Estacionamento gratuito<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wi-Fi gratuito<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-heart\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M462.3 62.6C407.5 15.9 326 24.3 275.7 76.2L256 96.5l-19.7-20.3C186.1 24.3 104.5 15.9 49.7 62.6c-62.8 53.6-66.1 149.8-9.9 207.9l193.5 199.8c12.5 12.9 32.8 12.9 45.3 0l193.5-199.8c56.3-58.1 53-154.3-9.8-207.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quartos para fam\u00edlias<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-smoking-ban\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M96 304c0 8.8 7.2 16 16 16h117.5l-96-96H112c-8.8 0-16 7.2-16 16v64zM256 0C114.6 0 0 114.6 0 256s114.6 256 256 256 256-114.6 256-256S397.4 0 256 0zm0 448c-105.9 0-192-86.1-192-192 0-41.4 13.3-79.7 35.7-111.1l267.4 267.4C335.7 434.7 297.4 448 256 448zm45.2-192H384v32h-50.8l-32-32zm111.1 111.1L365.2 320H400c8.8 0 16-7.2 16-16v-64c0-8.8-7.2-16-16-16H269.2L144.9 99.7C176.3 77.3 214.6 64 256 64c105.9 0 192 86.1 192 192 0 41.4-13.3 79.7-35.7 111.1zM320.6 128c-15.6 0-28.6-11.2-31.4-25.9-.7-3.6-4-6.1-7.7-6.1h-16.2c-5 0-8.7 4.5-8 9.4 4.6 30.9 31.2 54.6 63.3 54.6 15.6 0 28.6 11.2 31.4 25.9.7 3.6 4 6.1 7.7 6.1h16.2c5 0 8.7-4.5 8-9.4-4.6-30.9-31.2-54.6-63.3-54.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quartos para n\u00e3o fumantes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-coffee\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 384h192c53 0 96-43 96-96h32c70.6 0 128-57.4 128-128S582.6 32 512 32H120c-13.3 0-24 10.7-24 24v232c0 53 43 96 96 96zM512 96c35.3 0 64 28.7 64 64s-28.7 64-64 64h-32V96h32zm47.7 384H48.3c-47.6 0-61-64-36-64h583.3c25 0 11.8 64-35.9 64z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Caf\u00e9 da manh\u00e3<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2320\" class=\"elementor-element elementor-element-9ea7699 e-con-full e-flex e-con e-child\" data-id=\"9ea7699\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2320\" class=\"elementor-element elementor-element-ef4c0e1 e-con-full e-flex e-con e-child\" data-id=\"ef4c0e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d09539a elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d09539a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bath\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M32,384a95.4,95.4,0,0,0,32,71.09V496a16,16,0,0,0,16,16h32a16,16,0,0,0,16-16V480H384v16a16,16,0,0,0,16,16h32a16,16,0,0,0,16-16V455.09A95.4,95.4,0,0,0,480,384V336H32ZM496,256H80V69.25a21.26,21.26,0,0,1,36.28-15l19.27,19.26c-13.13,29.88-7.61,59.11,8.62,79.73l-.17.17A16,16,0,0,0,144,176l11.31,11.31a16,16,0,0,0,22.63,0L283.31,81.94a16,16,0,0,0,0-22.63L272,48a16,16,0,0,0-22.62,0l-.17.17c-20.62-16.23-49.83-21.75-79.73-8.62L150.22,20.28A69.25,69.25,0,0,0,32,69.25V256H16A16,16,0,0,0,0,272v16a16,16,0,0,0,16,16H496a16,16,0,0,0,16-16V272A16,16,0,0,0,496,256Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Quarto<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Guarda-roupa ou arm\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aquecimento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enxoval completo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8978aed elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8978aed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bath\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M32,384a95.4,95.4,0,0,0,32,71.09V496a16,16,0,0,0,16,16h32a16,16,0,0,0,16-16V480H384v16a16,16,0,0,0,16,16h32a16,16,0,0,0,16-16V455.09A95.4,95.4,0,0,0,480,384V336H32ZM496,256H80V69.25a21.26,21.26,0,0,1,36.28-15l19.27,19.26c-13.13,29.88-7.61,59.11,8.62,79.73l-.17.17A16,16,0,0,0,144,176l11.31,11.31a16,16,0,0,0,22.63,0L283.31,81.94a16,16,0,0,0,0-22.63L272,48a16,16,0,0,0-22.62,0l-.17.17c-20.62-16.23-49.83-21.75-79.73-8.62L150.22,20.28A69.25,69.25,0,0,0,32,69.25V256H16A16,16,0,0,0,0,272v16a16,16,0,0,0,16,16H496a16,16,0,0,0,16-16V272A16,16,0,0,0,496,256Z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Banheiro<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Banheiro privativo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Papel higi\u00eanico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Toalhas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Produtos de higiene pessoal gratuitos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Secador de cabelo (na recep\u00e7\u00e3o)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb82f03 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"eb82f03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-swimming-pool\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 416h-16c-26.04 0-45.8-8.42-56.09-17.9-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C461.8 407.58 442.04 416 416 416s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C269.8 407.58 250.04 416 224 416s-45.8-8.42-56.09-17.9c-8.9-8.21-19.66-14.1-31.77-14.1h-16.3c-12.11 0-22.87 5.89-31.77 14.1C77.8 407.58 58.04 416 32 416H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h16c38.62 0 72.72-12.19 96-31.84 23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84s72.72-12.19 96-31.84c23.28 19.66 57.38 31.84 96 31.84h16c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zm-400-32v-96h192v96c19.12 0 30.86-6.16 34.39-9.42 9.17-8.46 19.2-14.34 29.61-18.07V128c0-17.64 14.36-32 32-32s32 14.36 32 32v16c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-16c0-52.94-43.06-96-96-96s-96 43.06-96 96v96H224v-96c0-17.64 14.36-32 32-32s32 14.36 32 32v16c0 8.84 7.16 16 16 16h32c8.84 0 16-7.16 16-16v-16c0-52.94-43.06-96-96-96s-96 43.06-96 96v228.5c10.41 3.73 20.44 9.62 29.61 18.07 3.53 3.27 15.27 9.43 34.39 9.43z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Piscina ao ar livre<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aberta o ano todo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Piscina com bar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Piscina infantil<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cerca ao redor da piscina<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-119583d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"119583d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-envira\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 32c477.6 0 366.6 317.3 367.1 366.3L448 480h-26l-70.4-71.2c-39 4.2-124.4 34.5-214.4-37C47 300.3 52 214.7 0 32zm79.7 46c-49.7-23.5-5.2 9.2-5.2 9.2 45.2 31.2 66 73.7 90.2 119.9 31.5 60.2 79 139.7 144.2 167.7 65 28 34.2 12.5 6-8.5-28.2-21.2-68.2-87-91-130.2-31.7-60-61-118.6-144.2-158.1z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>\u00c1rea ao ar livre<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cadeiras \/ Guarda-sol<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sala com lareira<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c1rea para fogueira<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Jogos de tabuleiro<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2320\" class=\"elementor-element elementor-element-0501ef3 e-con-full e-flex e-con e-child\" data-id=\"0501ef3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c451f7 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6c451f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>M\u00eddia \/ Tecnologia<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV de tela plana<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef8d84 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2ef8d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Alimentos e bebidas<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Frigobar \/ Geladeira<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bar \/ Lanchonete - Funcionamento das 11h \u00e0s 23h<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Restaurante - Funcionamento das 17h \u00e0s 22h<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Refei\u00e7\u00f5es especiais para crian\u00e7as<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Refei\u00e7\u00f5es para dietas especiais (avisar com anteced\u00eancia)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">M\u00e1quina de vendas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66f7a4a elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"66f7a4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Internet<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acesso Wi-Fi dispon\u00edvel em todas as \u00e1reas, gratuitamente.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3af205c elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3af205c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-concierge-bell\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 130.54V112h16c8.84 0 16-7.16 16-16V80c0-8.84-7.16-16-16-16h-96c-8.84 0-16 7.16-16 16v16c0 8.84 7.16 16 16 16h16v18.54C115.49 146.11 32 239.18 32 352h448c0-112.82-83.49-205.89-192-221.46zM496 384H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h480c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Servi\u00e7os<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servi\u00e7o de limpeza di\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Recep\u00e7\u00e3o 24 horas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servi\u00e7o de transfer \/ Aluguel de carro (aux\u00edlio com reserva)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reserva de ingressos para Festival de Inverno de Campos do Jord\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c1rea para coworking \/ reuni\u00f5es<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dep\u00f3sito para bagagens<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2320\" class=\"elementor-element elementor-element-b4d3344 e-con-full e-flex e-con e-child\" data-id=\"b4d3344\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d306c2 elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4d306c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-info-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.043 8 8 119.083 8 256c0 136.997 111.043 248 248 248s248-111.003 248-248C504 119.083 392.957 8 256 8zm0 110c23.196 0 42 18.804 42 42s-18.804 42-42 42-42-18.804-42-42 18.804-42 42-42zm56 254c0 6.627-5.373 12-12 12h-88c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h12v-64h-12c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h64c6.627 0 12 5.373 12 12v100h12c6.627 0 12 5.373 12 12v24z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Geral<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c1rea espec\u00edfica para fumantes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ar-condicionado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quartos para fam\u00edlias<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quartos para n\u00e3o fumantes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-046b7db elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"046b7db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-lock\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 224h-24v-72C376 68.2 307.8 0 224 0S72 68.2 72 152v72H48c-26.5 0-48 21.5-48 48v192c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V272c0-26.5-21.5-48-48-48zm-104 0H152v-72c0-39.7 32.3-72 72-72s72 32.3 72 72v72z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Seguran\u00e7a<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Extintores de inc\u00eandio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CCTV fora da acomoda\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CCTV nas \u00e1reas comuns<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Seguran\u00e7a 24 horas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f1839b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1f1839b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-parking\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM240 320h-48v48c0 8.8-7.2 16-16 16h-32c-8.8 0-16-7.2-16-16V144c0-8.8 7.2-16 16-16h96c52.9 0 96 43.1 96 96s-43.1 96-96 96zm0-128h-48v64h48c17.6 0 32-14.4 32-32s-14.4-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Estacionamento<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Estacionamento gratuito. N\u00e3o necessita de reserva.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e31be0d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e31be0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-paw\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 224c-79.41 0-192 122.76-192 200.25 0 34.9 26.81 55.75 71.74 55.75 48.84 0 81.09-25.08 120.26-25.08 39.51 0 71.85 25.08 120.26 25.08 44.93 0 71.74-20.85 71.74-55.75C448 346.76 335.41 224 256 224zm-147.28-12.61c-10.4-34.65-42.44-57.09-71.56-50.13-29.12 6.96-44.29 40.69-33.89 75.34 10.4 34.65 42.44 57.09 71.56 50.13 29.12-6.96 44.29-40.69 33.89-75.34zm84.72-20.78c30.94-8.14 46.42-49.94 34.58-93.36s-46.52-72.01-77.46-63.87-46.42 49.94-34.58 93.36c11.84 43.42 46.53 72.02 77.46 63.87zm281.39-29.34c-29.12-6.96-61.15 15.48-71.56 50.13-10.4 34.65 4.77 68.38 33.89 75.34 29.12 6.96 61.15-15.48 71.56-50.13 10.4-34.65-4.77-68.38-33.89-75.34zm-156.27 29.34c30.94 8.14 65.62-20.45 77.46-63.87 11.84-43.42-3.64-85.21-34.58-93.36s-65.62 20.45-77.46 63.87c-11.84 43.42 3.64 85.22 34.58 93.36z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Pets<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Animais de estima\u00e7\u00e3o permitidos. Custos adicionais podem ser aplicados.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e1c291 elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9e1c291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-language\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M152.1 236.2c-3.5-12.1-7.8-33.2-7.8-33.2h-.5s-4.3 21.1-7.8 33.2l-11.1 37.5H163zM616 96H336v320h280c13.3 0 24-10.7 24-24V120c0-13.3-10.7-24-24-24zm-24 120c0 6.6-5.4 12-12 12h-11.4c-6.9 23.6-21.7 47.4-42.7 69.9 8.4 6.4 17.1 12.5 26.1 18 5.5 3.4 7.3 10.5 4.1 16.2l-7.9 13.9c-3.4 5.9-10.9 7.8-16.7 4.3-12.6-7.8-24.5-16.1-35.4-24.9-10.9 8.7-22.7 17.1-35.4 24.9-5.8 3.5-13.3 1.6-16.7-4.3l-7.9-13.9c-3.2-5.6-1.4-12.8 4.2-16.2 9.3-5.7 18-11.7 26.1-18-7.9-8.4-14.9-17-21-25.7-4-5.7-2.2-13.6 3.7-17.1l6.5-3.9 7.3-4.3c5.4-3.2 12.4-1.7 16 3.4 5 7 10.8 14 17.4 20.9 13.5-14.2 23.8-28.9 30-43.2H412c-6.6 0-12-5.4-12-12v-16c0-6.6 5.4-12 12-12h64v-16c0-6.6 5.4-12 12-12h16c6.6 0 12 5.4 12 12v16h64c6.6 0 12 5.4 12 12zM0 120v272c0 13.3 10.7 24 24 24h280V96H24c-13.3 0-24 10.7-24 24zm58.9 216.1L116.4 167c1.7-4.9 6.2-8.1 11.4-8.1h32.5c5.1 0 9.7 3.3 11.4 8.1l57.5 169.1c2.6 7.8-3.1 15.9-11.4 15.9h-22.9a12 12 0 0 1-11.5-8.6l-9.4-31.9h-60.2l-9.1 31.8c-1.5 5.1-6.2 8.7-11.5 8.7H70.3c-8.2 0-14-8.1-11.4-15.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Idiomas falados<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Portugu\u00eas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ingl\u00eas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2321\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2321\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Informa\u00e7\u00f5es de Hospedagem <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-d3c225b e-con-full e-flex e-con e-child\" data-id=\"d3c225b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-20e551f e-flex e-con-boxed e-con e-child\" data-id=\"20e551f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf6651 elementor-position-left elementor-vertical-align-middle elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"ecf6651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/entrada-e1729715766162.png\" class=\"attachment-full size-full wp-image-5103\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/entrada-e1729715766162.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/entrada-e1729715766162-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/entrada-e1729715766162-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Entrada<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5622d52 elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5622d52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"a53cbfa6de\">A partir de 14:00<\/div><div class=\"a53cbfa6de c967b9f746\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-001e8e6 e-flex e-con-boxed e-con e-child\" data-id=\"001e8e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-719d661 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"719d661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/sair.png\" class=\"attachment-full size-full wp-image-5101\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/sair.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/sair-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/sair-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sa\u00edda<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22186ca elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"22186ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>At\u00e9 12:00<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-0cc0574 e-flex e-con-boxed e-con e-child\" data-id=\"0cc0574\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14c693d elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"14c693d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/campainha-de-mesa.png\" class=\"attachment-full size-full wp-image-3951\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/campainha-de-mesa.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/campainha-de-mesa-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/campainha-de-mesa-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Recep\u00e7\u00e3o<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9d20cb elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a9d20cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>24 horas<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-f7999a2 e-flex e-con-boxed e-con e-child\" data-id=\"f7999a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9afb976 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"9afb976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2025\/03\/cafe.png\" class=\"attachment-full size-full wp-image-30108\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2025\/03\/cafe.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/03\/cafe-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/03\/cafe-150x150.png 150w, https:\/\/velinn.com\/wp-content\/uploads\/2025\/03\/cafe-12x12.png 12w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Caf\u00e9 da manh\u00e3<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15f79af elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"15f79af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das 8h \u00e0s 10:45<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-a0f80ca e-flex e-con-boxed e-con e-child\" data-id=\"a0f80ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15baf4b elementor-position-left elementor-vertical-align-middle elementor-vertical-align-top elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"15baf4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/08\/criancas-2.png\" class=\"attachment-full size-full wp-image-876\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/08\/criancas-2.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/08\/criancas-2-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/08\/criancas-2-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Crian\u00e7as e camas<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bcc905 elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9bcc905\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Pol\u00edticas para crian\u00e7as<\/strong><\/p><p>Crian\u00e7as de qualquer idade s\u00e3o bem-vindas.<\/p><p>Crian\u00e7as a partir de 6 anos ser\u00e3o cobradas como adultos nesta acomoda\u00e7\u00e3o.<\/p><p>Para ver os pre\u00e7os e as informa\u00e7\u00f5es de ocupa\u00e7\u00e3o certos, informe quantas crian\u00e7as fazem parte do seu grupo e a idade delas.<\/p><p><strong>Pol\u00edticas para ber\u00e7os e camas extras<\/strong><\/p><p>Ber\u00e7os e camas extras n\u00e3o est\u00e3o dispon\u00edveis nesta acomoda\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-ac517a9 e-flex e-con-boxed e-con e-child\" data-id=\"ac517a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a88565b elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"a88565b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"148\" height=\"147\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/Rectangle-27.png\" class=\"attachment-full size-full wp-image-5074\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pets<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77950ee elementor-widget elementor-widget-text-editor\" data-id=\"77950ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aceitamos animais de estima\u00e7\u00e3o de pequeno porte (com at\u00e9 8kg) em todas as acomoda\u00e7\u00f5es.<\/p><p>Saiba mais informa\u00e7\u00f5es em<a href=\"https:\/\/velinn.com\/pets\/\"><strong>\u00a0velinn.com\/pets<\/strong><\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-c97b789 e-flex e-con-boxed e-con e-child\" data-id=\"c97b789\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ca8172 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"1ca8172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes.png\" class=\"attachment-full size-full wp-image-5104\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Cancelamento\/ pr\u00e9-pagamento<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c3be2 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c5c3be2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>As pol\u00edticas de cancelamento e pr\u00e9-pagamento variam de acordo com a tarifa escolhida.<br \/>Saiba mais informa\u00e7\u00f5es em\u00a0<strong><a href=\"https:\/\/velinn.com\/politica-de-reservas-e-cancelamento\/\" target=\"_blank\" rel=\"noopener\">velinn.com\/politica-de-reservas-e-cancelamento<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-f799b37 e-flex e-con-boxed e-con e-child\" data-id=\"f799b37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b32614 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"8b32614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes.png\" class=\"attachment-full size-full wp-image-5104\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/informacoes-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Regras da Pousada<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f30fe51 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f30fe51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conhe\u00e7a nosso regulamento interno\u00a0<strong><a href=\"https:\/\/velinn.com\/regulamento-interno-contrato\/\" target=\"_blank\" rel=\"noopener\">velinn.com\/regulamento-interno-contrato<\/a><\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-b99e7bc e-flex e-con-boxed e-con e-child\" data-id=\"b99e7bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e492948 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"e492948\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/cartao-de-credito.png\" class=\"attachment-full size-full wp-image-2017\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/cartao-de-credito.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/cartao-de-credito-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/09\/cartao-de-credito-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Cart\u00f5es aceitos neste hotel<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2321\" class=\"elementor-element elementor-element-e65f39f e-con-full e-flex e-con e-child\" data-id=\"e65f39f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-526132a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"526132a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngwing.com_.png\" class=\"attachment-full size-full wp-image-5111\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngwing.com_.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngwing.com_-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngwing.com_-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d255781 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d255781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"629\" height=\"458\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-e1729721814991.png\" class=\"attachment-full size-full wp-image-5110\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-e1729721814991.png 629w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-e1729721814991-300x218.png 300w\" sizes=\"(max-width: 629px) 100vw, 629px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42c1cb5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"42c1cb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-1.png\" class=\"attachment-full size-full wp-image-5113\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-1.png 512w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-1-300x300.png 300w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-1-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-082edf3 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"082edf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"626\" height=\"458\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-2-e1729721845750.png\" class=\"attachment-full size-full wp-image-5114\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-2-e1729721845750.png 626w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/pngegg-2-e1729721845750-300x219.png 300w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17b92b5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"17b92b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/logo-hipercard-256.png\" class=\"attachment-full size-full wp-image-5115\" alt=\"\" srcset=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/logo-hipercard-256.png 256w, https:\/\/velinn.com\/wp-content\/uploads\/2024\/10\/logo-hipercard-256-150x150.png 150w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-306a24d elementor-widget elementor-widget-text-editor\" data-id=\"306a24d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cheque n\u00e3o \u00e9 aceito.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-885d620 e-flex e-con-boxed e-con e-parent\" data-id=\"885d620\" data-element_type=\"container\" data-e-type=\"container\" id=\"localizacao\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b34393f e-con-full e-flex e-con e-child\" data-id=\"b34393f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54ca969 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"54ca969\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">localiza\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f18ad92 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f18ad92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S.A.P.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4eb563 elementor-widget elementor-widget-text-editor\" data-id=\"d4eb563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nossa localiza\u00e7\u00e3o privilegiada oferece f\u00e1cil acesso \u00e0s maravilhas de Santo Ant\u00f4nio do Pinhal, sendo o ref\u00fagio ideal para quem busca ar-puro, tranquilidade e conforto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-831594d e-con-full e-flex e-con e-child\" data-id=\"831594d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a62ca1 text-center elementor-widget elementor-widget-tp-off-canvas\" data-id=\"5a62ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-off-canvas.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"plus-offcanvas-wrapper canvas-5a62ca1  \" data-canvas-id=\"canvas-5a62ca1\" data-settings={\"content_id\":\"5a62ca1\",\"transition\":\"popup\",\"direction\":\"popup\",\"esc_close\":\"yes\",\"body_click_close\":\"yes\",\"trigger\":\"yes\",\"tpageload\":\"no\",\"tscroll\":\"no\",\"scrollHeight\":\"\",\"texit\":\"no\",\"tinactivity\":\"no\",\"tpageviews\":\"no\",\"tpageviewscount\":\"\",\"tprevurl\":\"no\",\"previousUrl\":\"\",\"textraclick\":\"no\",\"extraId\":\"\",\"extraIdClose\":\"\",\"inactivitySec\":\"\",\"sr\":\"\",\"srxtime\":\"\",\"srxdays\":\"\"}   ><div class=\"offcanvas-toggle-wrap\"><div class=\"offcanvas-toggle-btn toggle-button-style  \"><span class=\"btn-text\">Mostrar no mapa<\/span><\/div><\/div><style>.plus-5a62ca1-open .plus-5a62ca1.plus-canvas-content-wrap:not(.plus-popup).plus-visible { -webkit-transform: translate3d(0,0,0); transform: translate3d(0,0,0); }<\/style><div class=\"plus-canvas-content-wrap    tp-outer-yes tp-popup-dir-center plus-5a62ca1 plus-popup plus-popup \"><div class=\"plus-offcanvas-header direction-right \"><div class=\"plus-offcanvas-close plus-offcanvas-close-5a62ca1 \" role=\"button\"><\/div><\/div><div class=\"plus-content-editor\"><style>.elementor-34835 .elementor-element.elementor-element-e5aedb6{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;}.elementor-widget-osm-map-elementor .marker-title .elementor-heading-title{color:var( --e-global-color-secondary );font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );}.elementor-widget-osm-map-elementor .marker-content .marker-description{color:var( --e-global-color-text );font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );}.elementor-widget-osm-map-elementor .marker-button .elementor-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );fill:var( --e-global-color-secondary );color:var( --e-global-color-secondary );background-color:var( --e-global-color-primary );}.elementor-34835 .elementor-element.elementor-element-47a7482 .osm-map-container{width:100%;height:360px;z-index:0;}.elementor-34835 .elementor-element.elementor-element-47a7482 .marker-tooltip .marker-title{text-align:center;}.elementor-34835 .elementor-element.elementor-element-47a7482 .marker-title .elementor-heading-title{color:var( --e-global-color-accent );font-family:\"Poppins\", Sans-serif;font-weight:400;margin:0px 0px 0px 0px;}.elementor-34835 .elementor-element.elementor-element-47a7482 .marker-content .marker-description{text-align:center;font-family:\"Poppins\", Sans-serif;font-weight:400;padding:0px 0px 5px 0px;}.elementor-34835 .elementor-element.elementor-element-47a7482 .marker-content .marker-button{text-align:center;}.elementor-34835 .elementor-element.elementor-element-47a7482 .marker-button .elementor-button{fill:var( --e-global-color-fd21468 );color:var( --e-global-color-fd21468 );background-color:var( --e-global-color-accent );}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"34835\" class=\"elementor elementor-34835\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-e5aedb6 e-con-full e-flex e-con e-parent\" data-id=\"e5aedb6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47a7482 elementor-widget elementor-widget-osm-map-elementor\" data-id=\"47a7482\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"osm-map-elementor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"osm-map-47a7482\" \n        class=\"osm-map-container\" \n        data-center=\"-22.772681882171,-45.695992033605\"><\/div>        <script type=\"text\/javascript\">\n                    <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><script type=\"text\/javascript\">jQuery(document).ready(function(i){\n\t\t\t\t\t\t\t\t\t\"use strict\";\n\t\t\t\t\t\t\t\t\tjQuery(\".plus-content-editor a:not(.dropdown-toggle),.plus-content-editor .tp-search-filter .tp-range-silder\").on(\"click\",function(){\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\tjQuery(this).closest(\".plus-canvas-content-wrap\").find( \".plus-offcanvas-close\").trigger( \"click\" );\n\t\t\t\t\t\t\t\t\t})\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\tjQuery(\".plus-content-editor .tp-search-filter .tp-search-form\").on(\"change\",function(){\n\t\t\t\t\t\t\t\t\t\tjQuery(this).closest(\".plus-canvas-content-wrap\").find( \".plus-offcanvas-close\").trigger( \"click\" );\n\t\t\t\t\t\t\t\t\t})});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e20ea1 e-con-full e-flex e-con e-child\" data-id=\"8e20ea1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0cfbf5 elementor-hidden-desktop elementor-hidden-laptop elementor-widget elementor-widget-n-accordion\" data-id=\"d0cfbf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2180\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2180\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Proximidades da acomoda\u00e7\u00e3o <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2180\" class=\"elementor-element elementor-element-550a9b8 e-con-full e-flex e-con e-child\" data-id=\"550a9b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0491a3 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b0491a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>O que h\u00e1 por perto?<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Centro de Lazer 8 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parque das Cerejeiras 13 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Museu Fel\u00edcia Leirner 13 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pal\u00e1cio da Boa Vista 14 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parque de C\u00e3es do Centro Veterin\u00e1rio de Campos do Jord\u00e3o 16 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parque Amantikir 16 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Amantikir 19 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Casa da Xilogravura 19 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensils\" viewBox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.9 15.2c.8 4.7 16.1 94.5 16.1 128.8 0 52.3-27.8 89.6-68.9 104.6L168 486.7c.7 13.7-10.2 25.3-24 25.3H80c-13.7 0-24.7-11.5-24-25.3l12.9-238.1C27.7 233.6 0 196.2 0 144 0 109.6 15.3 19.9 16.1 15.2 19.3-5.1 61.4-5.4 64 16.3v141.2c1.3 3.4 15.1 3.2 16 0 1.4-25.3 7.9-139.2 8-141.8 3.3-20.8 44.7-20.8 47.9 0 .2 2.7 6.6 116.5 8 141.8.9 3.2 14.8 3.4 16 0V16.3c2.6-21.6 44.8-21.4 48-1.1zm119.2 285.7l-15 185.1c-1.2 14 9.9 26 23.9 26h56c13.3 0 24-10.7 24-24V24c0-13.2-10.7-24-24-24-82.5 0-221.4 178.5-64.9 300.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Restaurantes e caf\u00e9s<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Restaurante \u2022 Mina Restaurante 6 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Restaurante \u2022 Bistro Seu Benedit\u00fa 5 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Restaurante \u2022 Fazenda Velha 5 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8b9f51 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d8b9f51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mountain\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.92 462.7l-288-448C341.03 5.54 330.89 0 320 0s-21.03 5.54-26.92 14.7l-288 448a32.001 32.001 0 0 0-1.17 32.64A32.004 32.004 0 0 0 32 512h576c11.71 0 22.48-6.39 28.09-16.67a31.983 31.983 0 0 0-1.17-32.63zM320 91.18L405.39 224H320l-64 64-38.06-38.06L320 91.18z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Belezas naturais<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cachoeira \u2022 Cachoeira do Lageado 6 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pico \u2022 Morro do Baepi 12 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-umbrella-beach\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M115.38 136.9l102.11 37.18c35.19-81.54 86.21-144.29 139-173.7-95.88-4.89-188.78 36.96-248.53 111.8-6.69 8.4-2.66 21.05 7.42 24.72zm132.25 48.16l238.48 86.83c35.76-121.38 18.7-231.66-42.63-253.98-7.4-2.7-15.13-4-23.09-4-58.02.01-128.27 69.17-172.76 171.15zM521.48 60.5c6.22 16.3 10.83 34.6 13.2 55.19 5.74 49.89-1.42 108.23-18.95 166.98l102.62 37.36c10.09 3.67 21.31-3.43 21.57-14.17 2.32-95.69-41.91-187.44-118.44-245.36zM560 447.98H321.06L386 269.5l-60.14-21.9-72.9 200.37H16c-8.84 0-16 7.16-16 16.01v32.01C0 504.83 7.16 512 16 512h544c8.84 0 16-7.17 16-16.01v-32.01c0-8.84-7.16-16-16-16z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Transporte P\u00fablico<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Abern\u00e9ssia (Campos do Jord\u00e3o) 17 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plane-departure\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 448H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h608c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM80.55 341.27c6.28 6.84 15.1 10.72 24.33 10.71l130.54-.18a65.62 65.62 0 0 0 29.64-7.12l290.96-147.65c26.74-13.57 50.71-32.94 67.02-58.31 18.31-28.48 20.3-49.09 13.07-63.65-7.21-14.57-24.74-25.27-58.25-27.45-29.85-1.94-59.54 5.92-86.28 19.48l-98.51 49.99-218.7-82.06a17.799 17.799 0 0 0-18-1.11L90.62 67.29c-10.67 5.41-13.25 19.65-5.17 28.53l156.22 98.1-103.21 52.38-72.35-36.47a17.804 17.804 0 0 0-16.07.02L9.91 230.22c-10.44 5.3-13.19 19.12-5.57 28.08l76.21 82.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Aeroportos mais pr\u00f3ximos<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aeroporto Regional de S\u00e3o Jos\u00e9 dos Campos 84 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aeroporto de Guaratinguet\u00e1 92 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1eaecca elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1eaecca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>O que h\u00e1 por perto?<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Centro de Lazer 8 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parque das Cerejeiras 13 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Museu Fel\u00edcia Leirner 13 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pal\u00e1cio da Boa Vista 14 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parque de C\u00e3es do Centro Veterin\u00e1rio de Campos do Jord\u00e3o 16 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parque Amantikir 16 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Amantikir 19 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Casa da Xilogravura 19 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensils\" viewBox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.9 15.2c.8 4.7 16.1 94.5 16.1 128.8 0 52.3-27.8 89.6-68.9 104.6L168 486.7c.7 13.7-10.2 25.3-24 25.3H80c-13.7 0-24.7-11.5-24-25.3l12.9-238.1C27.7 233.6 0 196.2 0 144 0 109.6 15.3 19.9 16.1 15.2 19.3-5.1 61.4-5.4 64 16.3v141.2c1.3 3.4 15.1 3.2 16 0 1.4-25.3 7.9-139.2 8-141.8 3.3-20.8 44.7-20.8 47.9 0 .2 2.7 6.6 116.5 8 141.8.9 3.2 14.8 3.4 16 0V16.3c2.6-21.6 44.8-21.4 48-1.1zm119.2 285.7l-15 185.1c-1.2 14 9.9 26 23.9 26h56c13.3 0 24-10.7 24-24V24c0-13.2-10.7-24-24-24-82.5 0-221.4 178.5-64.9 300.9z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Restaurantes e caf\u00e9s<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Restaurante \u2022 Mina Restaurante 6 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Restaurante \u2022 Bistro Seu Benedit\u00fa 5 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Restaurante \u2022 Fazenda Velha 5 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f38220 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-hidden-tablet elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6f38220\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mountain\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.92 462.7l-288-448C341.03 5.54 330.89 0 320 0s-21.03 5.54-26.92 14.7l-288 448a32.001 32.001 0 0 0-1.17 32.64A32.004 32.004 0 0 0 32 512h576c11.71 0 22.48-6.39 28.09-16.67a31.983 31.983 0 0 0-1.17-32.63zM320 91.18L405.39 224H320l-64 64-38.06-38.06L320 91.18z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Belezas naturais<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cachoeira \u2022 Cachoeira do Lageado 6 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pico \u2022 Morro do Baepi 12 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-umbrella-beach\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M115.38 136.9l102.11 37.18c35.19-81.54 86.21-144.29 139-173.7-95.88-4.89-188.78 36.96-248.53 111.8-6.69 8.4-2.66 21.05 7.42 24.72zm132.25 48.16l238.48 86.83c35.76-121.38 18.7-231.66-42.63-253.98-7.4-2.7-15.13-4-23.09-4-58.02.01-128.27 69.17-172.76 171.15zM521.48 60.5c6.22 16.3 10.83 34.6 13.2 55.19 5.74 49.89-1.42 108.23-18.95 166.98l102.62 37.36c10.09 3.67 21.31-3.43 21.57-14.17 2.32-95.69-41.91-187.44-118.44-245.36zM560 447.98H321.06L386 269.5l-60.14-21.9-72.9 200.37H16c-8.84 0-16 7.16-16 16.01v32.01C0 504.83 7.16 512 16 512h544c8.84 0 16-7.17 16-16.01v-32.01c0-8.84-7.16-16-16-16z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Transporte P\u00fablico<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Abern\u00e9ssia (Campos do Jord\u00e3o) 17 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plane-departure\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 448H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h608c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM80.55 341.27c6.28 6.84 15.1 10.72 24.33 10.71l130.54-.18a65.62 65.62 0 0 0 29.64-7.12l290.96-147.65c26.74-13.57 50.71-32.94 67.02-58.31 18.31-28.48 20.3-49.09 13.07-63.65-7.21-14.57-24.74-25.27-58.25-27.45-29.85-1.94-59.54 5.92-86.28 19.48l-98.51 49.99-218.7-82.06a17.799 17.799 0 0 0-18-1.11L90.62 67.29c-10.67 5.41-13.25 19.65-5.17 28.53l156.22 98.1-103.21 52.38-72.35-36.47a17.804 17.804 0 0 0-16.07.02L9.91 230.22c-10.44 5.3-13.19 19.12-5.57 28.08l76.21 82.97z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Aeroportos mais pr\u00f3ximos<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aeroporto Regional de S\u00e3o Jos\u00e9 dos Campos 84 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aeroporto de Guaratinguet\u00e1 92 km<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e8b76a e-con-full e-flex e-con e-parent\" data-id=\"3e8b76a\" data-element_type=\"container\" data-e-type=\"container\" id=\"depoimentos\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5c1f10 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a5c1f10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9500\" class=\"elementor elementor-9500\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-a73e436 e-flex e-con-boxed e-con e-parent\" data-id=\"a73e436\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eb1e52b e-flex e-con-boxed e-con e-child\" data-id=\"eb1e52b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc4b76 elementor-widget elementor-widget-text-editor\" data-id=\"4dc4b76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O QUE DIZEM NOSSOS H\u00d3SPEDES<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d87b879 elementor-testimonial--layout-image_stacked elementor-testimonial--skin-default elementor-testimonial--align-center elementor-arrows-yes elementor-widget elementor-widget-testimonial-carousel\" data-id=\"d87b879\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<h3  style=\"font-family:Poppins; font-size:20px; \">  F\u00e9rias em Casal\n\n<\/h3>\n\u2028\n\n\n&#8220;Pousada muito charmosa, estilo r\u00fastico, bastante espa\u00e7o para estacionar, atendimento excelente, sr Mariano foi muito simp\u00e1tico e atencioso, roupa de cama e sabonete cheirosos, aquecedor nos quartos, janela de madeira que deixa o quarto bem escuro, chuveiro com bastante press\u00e3o e temperatura muit boa, caf\u00e9 da manh\u00e3 impec\u00e1vel com tres tipos de sucos naturais, frutas, doces, e diversos tipos de p\u00e3es para rechear. Gostamos muito da hospedagem.&#8221; \t\t\t\t\t\t\t \n<br><br>\n<img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/10\/starspequena.png\">\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/unnamed-3-1.png\" alt=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__title\">Eric Hoelzle<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<h3  style=\"font-family:Poppins; font-size:20px; \">Viagem em Casal\n<\/h3>\n\n\n&#8220;A pousada \u00e9 linda e aconchegante. O destaque com certeza vai para os funcion\u00e1rios, que s\u00e3o simp\u00e1ticos e muito atenciosos, especialmente o sr. Mariano. O custo-benef\u00edcio \u00e9 realmente bom e o caf\u00e9 da manh\u00e3 \u00e9 uma del\u00edcia. A limpeza era impec\u00e1vel e o chuveiro bem quente. Tivemos dois problemas pontuais no quarto onde ficamos: o barulho (que pesa para quem tem sono leve) e o cheiro de fritura, porque est\u00e1vamos bem em cima da cozinha. De resto, tudo muito bom.&#8221; \t\t\t\t\t\n<br><br>\n<img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/10\/starspequena.png\">\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/unnamed-4-1.png\" alt=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__title\">Ana Carolina Av\u00f3lio<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<h3  style=\"font-family:Poppins; font-size:20px; \">F\u00e9rias em Casal\n\n<\/h3>\n\n\n&#8220;Os quartos s\u00e3o simples, mas limpos. Atendimento foi \u00f3timo. Caf\u00e9 da manh\u00e3 completo tamb\u00e9m. O estilo r\u00fastico confere um charme. Piscina estava limpa.&#8221; \t\t\t\t\t<br><br>\n<img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/10\/starspequena.png\">\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/2024\/12\/unnamed-5-1.png\" alt=\"\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__title\">Roberto Araujo Chahad<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a442b2 elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"3a442b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76013d2 elementor-widget elementor-widget-heading\" data-id=\"76013d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">perguntas frequentes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9af69cd elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-widget elementor-widget-heading\" data-id=\"9af69cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7b8670 elementor-widget elementor-widget-n-accordion\" data-id=\"d7b8670\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2260\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2260\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Qual o hor\u00e1rio de Check-in e Check-out? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2260\" class=\"elementor-element elementor-element-79ffe01 e-con-full e-flex e-con e-child\" data-id=\"79ffe01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08d8a34 elementor-widget elementor-widget-text-editor\" data-id=\"08d8a34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"c6e1dbf31b\"><div class=\"d204b23899\"><div class=\"e1eebb6a1e\"><strong>Entrada<\/strong><\/div><\/div><\/div><div class=\"f565581f7e\"><div class=\"a53cbfa6de\"><em>\u00c0S 14:00<\/em><\/div><\/div><div>\u00a0<\/div><div><div class=\"c6e1dbf31b\"><div class=\"d204b23899\"><div class=\"e1eebb6a1e\"><strong>Sa\u00edda<\/strong><\/div><\/div><\/div><div class=\"f565581f7e\"><div class=\"a53cbfa6de\"><em>Das 09:00 \u00e0s 12:00<\/em><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2261\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2261\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> O hotel \u00e9 Pet Friendly? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2261\" class=\"elementor-element elementor-element-7f3fe41 e-con-full e-flex e-con e-child\" data-id=\"7f3fe41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b78c3d elementor-widget elementor-widget-text-editor\" data-id=\"9b78c3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>N\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2262\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2262\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Existe restri\u00e7\u00e3o de idade? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-down\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2262\" class=\"elementor-element elementor-element-6e17dd1 e-con-full e-flex e-con e-child\" data-id=\"6e17dd1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f989f01 elementor-widget elementor-widget-text-editor\" data-id=\"f989f01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A idade m\u00ednima para check-in \u00e9 18 anos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-779582b e-flex e-con-boxed e-con e-parent\" data-id=\"779582b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d43dffd elementor-widget elementor-widget-heading\" data-id=\"d43dffd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">As melhores op\u00e7\u00f5es de hospedagem<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0176107 elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-widget elementor-widget-heading\" data-id=\"0176107\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">explore nossas hospedagens<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21658cb elementor-arrows-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"21658cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:11793,&quot;slides_to_show&quot;:&quot;4&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show_laptop&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t<style id=\"loop-11793\">.elementor-11793 .elementor-element.elementor-element-6e08d10{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;}.elementor-widget-theme-post-featured-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );}.elementor-11793 .elementor-element.elementor-element-67d79a7 img{border-radius:10px 10px 10px 10px;}.elementor-widget-theme-post-title .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-11793 .elementor-element.elementor-element-56f21ac{text-align:center;}.elementor-11793 .elementor-element.elementor-element-56f21ac .elementor-heading-title{font-family:\"Poppins\", Sans-serif;font-size:17px;font-weight:500;text-transform:uppercase;color:var( --e-global-color-text );}.elementor-widget-icon-list .elementor-icon-list-item:not(:last-child):after{border-color:var( --e-global-color-text );}.elementor-widget-icon-list .elementor-icon-list-icon i{color:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-icon svg{fill:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );}.elementor-widget-icon-list .elementor-icon-list-text{color:var( --e-global-color-secondary );}.elementor-11793 .elementor-element.elementor-element-1be08d0 .elementor-icon-list-icon i{color:var( --e-global-color-primary );transition:color 0.3s;}.elementor-11793 .elementor-element.elementor-element-1be08d0 .elementor-icon-list-icon svg{fill:var( --e-global-color-primary );transition:fill 0.3s;}.elementor-11793 .elementor-element.elementor-element-1be08d0{--e-icon-list-icon-size:14px;--icon-vertical-offset:0px;}.elementor-11793 .elementor-element.elementor-element-1be08d0 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-11793 .elementor-element.elementor-element-1be08d0 .elementor-icon-list-item > a{font-family:\"Montserrat\", Sans-serif;font-size:16px;font-weight:400;text-transform:uppercase;}.elementor-11793 .elementor-element.elementor-element-1be08d0 .elementor-icon-list-text{transition:color 0.3s;}.elementor-widget-button .elementor-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );background-color:var( --e-global-color-accent );}.elementor-11793 .elementor-element.elementor-element-32c1c41 .elementor-button{font-family:\"Poppins\", Sans-serif;font-weight:500;fill:var( --e-global-color-fd21468 );color:var( --e-global-color-fd21468 );border-radius:100px 100px 100px 100px;}.elementor-11793 .elementor-element.elementor-element-e8a39fa{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;}@media(max-width:1366px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-size:var( --e-global-typography-text-font-size );}}@media(max-width:1024px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-size:var( --e-global-typography-text-font-size );}}@media(max-width:767px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-size:var( --e-global-typography-text-font-size );}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"11793\" class=\"elementor elementor-11793 swiper-slide e-loop-item e-loop-item-11766 post-11766 post type-post status-publish format-standard has-post-thumbnail hentry category-hotel-pousada category-montanhas category-pet-friendly category-santo-antonio-do-pinhal\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-6e08d10 e-flex e-con-boxed e-con e-parent\" data-id=\"6e08d10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67d79a7 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67d79a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-3-qxysfxbrha80npoqadhdczmk5kalctiiu8w00vmluq-qy0f0ljg409fkpjsfh0l1ydmrkjufvy42e4owf00c8.webp\" title=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-3-qxysfxbrha80npoqadhdczmk5kalctiiu8w00vmluq\" alt=\"Velinn_Pousada_Cesar_Santo_Antonio_do_Pinhal_Propriedade-3-qxysfxbrha80npoqadhdczmk5kalctiiu8w00vmluq\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f21ac elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"56f21ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Velinn Pousada Cesar<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1be08d0 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1be08d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Santo Ant\u00f4nio do Pinhal - SP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c1c41 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"32c1c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinn.com\/velinn-pousada-cesar-santo-antonio-do-pinhal\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SAIBA MAIS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e8a39fa e-flex e-con-boxed e-con e-parent\" data-id=\"e8a39fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"11793\" class=\"elementor elementor-11793 swiper-slide e-loop-item e-loop-item-11762 post-11762 post type-post status-publish format-standard has-post-thumbnail hentry category-hotel-pousada category-pet-friendly category-santo-antonio-do-pinhal\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-6e08d10 e-flex e-con-boxed e-con e-parent\" data-id=\"6e08d10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67d79a7 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"67d79a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/velinn.com\/wp-content\/uploads\/elementor\/thumbs\/Velinn_Hotel_Fazenda_Fonte_das_Hortensias_Propriedade_Piscina-1-1-qy0evsl56hoo8gj0he98b60tgo8b3kvi2m3cli4g54.jpg\" title=\"Velinn_Hotel_Fazenda_Fonte_das_Hortensias_Propriedade_Piscina-1\" alt=\"Velinn_Hotel_Fazenda_Fonte_das_Hortensias_Propriedade_Piscina-1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f21ac elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"56f21ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Velinn Hotel Fazenda Fonte das Hort\u00eansias<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1be08d0 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1be08d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Santo Ant\u00f4nio do Pinhal - SP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32c1c41 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"32c1c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/velinn.com\/velinn-hotel-fazenda-fonte-das-hortensias-santo-antonio-do-pinhal\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SAIBA MAIS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e8a39fa e-flex e-con-boxed e-con e-parent\" data-id=\"e8a39fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ed8b6e e-con-full e-flex e-con e-parent\" data-id=\"8ed8b6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57fd110 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"57fd110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"910\" class=\"elementor elementor-910\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-9f3f764 e-flex e-con-boxed e-con e-parent\" data-id=\"9f3f764\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a40cdf5 e-flex e-con-boxed e-con e-child\" data-id=\"a40cdf5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75c3889 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"75c3889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RECEBA AS MELHORES OFERTAS NO SEU E-MAIL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14b59e5 elementor-widget__width-inherit elementor-widget elementor-widget-html\" data-id=\"14b59e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe\r\n    src=\"https:\/\/api.reprotel.com.br\/widget\/form\/Ij7QrhIdqboRhbZxxzmg\"\r\n    style=\"width:100%;height:100%;border:none;border-radius:0px\"\r\n    id=\"inline-Ij7QrhIdqboRhbZxxzmg\" \r\n    data-layout=\"{'id':'INLINE'}\"\r\n    data-trigger-type=\"alwaysShow\"\r\n    data-trigger-value=\"\"\r\n    data-activation-type=\"alwaysActivated\"\r\n    data-activation-value=\"\"\r\n    data-deactivation-type=\"neverDeactivate\"\r\n    data-deactivation-value=\"\"\r\n    data-form-name=\"Newsletter - Site\"\r\n    data-height=\"460\"\r\n    data-layout-iframe-id=\"inline-Ij7QrhIdqboRhbZxxzmg\"\r\n    data-form-id=\"Ij7QrhIdqboRhbZxxzmg\"\r\n    title=\"Newsletter - Site\"\r\n        >\r\n<\/iframe>\r\n<script src=\"https:\/\/api.reprotel.com.br\/js\/form_embed.js\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rodovia SP50, Km 163-S\/N, Santo Ant\u00f4nio do Pinhal, CEP 12450-000, Brasil SIMULAR RESERVA mais 37 fotos Destaques Restaurante Duas Piscinas Pet Friendly Wi-Fi Quartos para fam\u00edlias Caf\u00e9 da Manh\u00e3 um pouco mais Com mais de 70 anos de hist\u00f3ria, a Velinn Pousada C\u00e9sar \u00e9 o ref\u00fagio perfeito para quem busca tranquilidade e conforto em meio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"depoimento":[],"class_list":["post-8991","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/pages\/8991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/comments?post=8991"}],"version-history":[{"count":21,"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/pages\/8991\/revisions"}],"predecessor-version":[{"id":45022,"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/pages\/8991\/revisions\/45022"}],"wp:attachment":[{"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/media?parent=8991"}],"wp:term":[{"taxonomy":"depoimento","embeddable":true,"href":"https:\/\/velinn.com\/es\/wp-json\/wp\/v2\/depoimento?post=8991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}